{"id":430,"date":"2024-02-14T09:15:31","date_gmt":"2024-02-14T08:15:31","guid":{"rendered":"https:\/\/www.txakolibengoetxe.com\/pribatutasun-politika\/"},"modified":"2024-03-19T17:08:31","modified_gmt":"2024-03-19T16:08:31","slug":"pribatutasun-politika","status":"publish","type":"page","link":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/","title":{"rendered":"Pribatutasun-politika"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nor gara?<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\"> <\/strong>La direcci\u00f3n de nuestra web es: http:\/\/www.txakolibengoetxe.com.<\/p>\n\n<h2 class=\"wp-block-heading\">Comentarios<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Cuando los visitantes dejan comentarios en la web, recopilamos los datos que se muestran en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agentes de usuario del navegador para ayudar a la detecci\u00f3n de spam.<\/p>\n\n<p>Una cadena an\u00f3nima creada a partir de tu direcci\u00f3n de correo electr\u00f3nico (tambi\u00e9n llamada hash) puede ser proporcionada al servicio de Gravatar para ver si la est\u00e1s usando. La pol\u00edtica de privacidad del servicio Gravatar est\u00e1 disponible aqu\u00ed: https:\/\/automattic.com\/privacy\/. Despu\u00e9s de la aprobaci\u00f3n de tu comentario, la imagen de tu perfil es visible para el p\u00fablico en el contexto de tu comentario.<\/p>\n\n<h2 class=\"wp-block-heading\">Medios<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Si subes im\u00e1genes a la web, deber\u00edas evitar subir im\u00e1genes con datos de ubicaci\u00f3n (GPS EXIF) incluidos. Los visitantes de la web pueden descargar y extraer cualquier dato de ubicaci\u00f3n de las im\u00e1genes de la web.<\/p>\n\n<h2 class=\"wp-block-heading\">Cookies<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Si dejas un comentario en nuestro sitio puedes elegir guardar tu nombre, direcci\u00f3n de correo electr\u00f3nico y web en cookies. Esto es para tu comodidad, para que no tengas que volver a rellenar tus datos cuando dejes otro comentario. Estas cookies tendr\u00e1n una duraci\u00f3n de un a\u00f1o.<\/p>\n\n<p>Si tienes una cuenta y te conectas a este sitio, instalaremos una cookie temporal para determinar si tu navegador acepta cookies. Esta cookie no contiene datos personales y se elimina al cerrar el navegador.<\/p>\n\n<p>Cuando accedas, tambi\u00e9n instalaremos varias cookies para guardar tu informaci\u00f3n de acceso y tus opciones de visualizaci\u00f3n de pantalla. Las cookies de acceso duran dos d\u00edas, y las cookies de opciones de pantalla duran un a\u00f1o. Si seleccionas \u00abRecu\u00e9rdarme\u00bb, tu acceso perdurar\u00e1 durante dos semanas. Si sales de tu cuenta, las cookies de acceso se eliminar\u00e1n.<\/p>\n\n<p>Si editas o publicas un art\u00edculo se guardar\u00e1 una cookie adicional en tu navegador. Esta cookie no incluye datos personales y simplemente indica el ID del art\u00edculo que acabas de editar. Caduca despu\u00e9s de 1 d\u00eda.<\/p>\n\n<h2 class=\"wp-block-heading\">Contenido incrustado de otros sitios web<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Los art\u00edculos de este sitio pueden incluir contenido incrustado (por ejemplo, v\u00eddeos, im\u00e1genes, art\u00edculos, etc.). El contenido incrustado de otras webs se comporta exactamente de la misma manera que si el visitante hubiera visitado la otra web.<\/p>\n\n<p>Estas web pueden recopilar datos sobre ti, utilizar cookies, incrustar un seguimiento adicional de terceros, y supervisar tu interacci\u00f3n con ese contenido incrustado, incluido el seguimiento de tu interacci\u00f3n con el contenido incrustado si tienes una cuenta y est\u00e1s conectado a esa web.<\/p>\n\n<h2 class=\"wp-block-heading\">Con qui\u00e9n compartimos tus datos<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Si solicitas un restablecimiento de contrase\u00f1a, tu direcci\u00f3n IP ser\u00e1 incluida en el correo electr\u00f3nico de restablecimiento.<\/p>\n\n<h2 class=\"wp-block-heading\">Cu\u00e1nto tiempo conservamos tus datos<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Si dejas un comentario, el comentario y sus metadatos se conservan indefinidamente. Esto es para que podamos reconocer y aprobar comentarios sucesivos autom\u00e1ticamente, en lugar de mantenerlos en una cola de moderaci\u00f3n.<\/p>\n\n<p>De los usuarios que se registran en nuestra web (si los hay), tambi\u00e9n almacenamos la informaci\u00f3n personal que proporcionan en su perfil de usuario. Todos los usuarios pueden ver, editar o eliminar su informaci\u00f3n personal en cualquier momento (excepto que no pueden cambiar su nombre de usuario). Los administradores de la web tambi\u00e9n pueden ver y editar esa informaci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 derechos tienes sobre tus datos<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Si tienes una cuenta o has dejado comentarios en esta web, puedes solicitar recibir un archivo de exportaci\u00f3n de los datos personales que tenemos sobre ti, incluyendo cualquier dato que nos hayas proporcionado. Tambi\u00e9n puedes solicitar que eliminemos cualquier dato personal que tengamos sobre ti. Esto no incluye ning\u00fan dato que estemos obligados a conservar con fines administrativos, legales o de seguridad.<\/p>\n\n<h2 class=\"wp-block-heading\">D\u00f3nde se env\u00edan tus datos<\/h2>\n\n<p><strong class=\"privacy-policy-tutorial\">Texto sugerido: <\/strong>Los comentarios de los visitantes puede que los revise un servicio de detecci\u00f3n autom\u00e1tica de spam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nor gara? La direcci\u00f3n de nuestra web es: http:\/\/www.txakolibengoetxe.com. Comentarios Texto sugerido: Cuando los visitantes dejan comentarios en la web, recopilamos los datos que se muestran en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agentes de usuario del navegador para ayudar a la detecci\u00f3n de spam. Una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-430","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pribatutasun-politika - Txakoli Bengoetxe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pribatutasun-politika - Txakoli Bengoetxe\" \/>\n<meta property=\"og:description\" content=\"Nor gara? La direcci\u00f3n de nuestra web es: http:\/\/www.txakolibengoetxe.com. Comentarios Texto sugerido: Cuando los visitantes dejan comentarios en la web, recopilamos los datos que se muestran en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agentes de usuario del navegador para ayudar a la detecci\u00f3n de spam. Una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/\" \/>\n<meta property=\"og:site_name\" content=\"Txakoli Bengoetxe\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T16:08:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.txakolibengoetxe.com\/wp-content\/uploads\/2024\/03\/Quienes-somos-raices.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/\",\"url\":\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/\",\"name\":\"Pribatutasun-politika - Txakoli Bengoetxe\",\"isPartOf\":{\"@id\":\"https:\/\/www.txakolibengoetxe.com\/eu\/#website\"},\"datePublished\":\"2024-02-14T08:15:31+00:00\",\"dateModified\":\"2024-03-19T16:08:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.txakolibengoetxe.com\/eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pribatutasun-politika\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.txakolibengoetxe.com\/eu\/#website\",\"url\":\"https:\/\/www.txakolibengoetxe.com\/eu\/\",\"name\":\"Txakoli Bengoetxe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.txakolibengoetxe.com\/eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pribatutasun-politika - Txakoli Bengoetxe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/","og_locale":"eu_ES","og_type":"article","og_title":"Pribatutasun-politika - Txakoli Bengoetxe","og_description":"Nor gara? La direcci\u00f3n de nuestra web es: http:\/\/www.txakolibengoetxe.com. Comentarios Texto sugerido: Cuando los visitantes dejan comentarios en la web, recopilamos los datos que se muestran en el formulario de comentarios, as\u00ed como la direcci\u00f3n IP del visitante y la cadena de agentes de usuario del navegador para ayudar a la detecci\u00f3n de spam. Una [&hellip;]","og_url":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/","og_site_name":"Txakoli Bengoetxe","article_modified_time":"2024-03-19T16:08:31+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.txakolibengoetxe.com\/wp-content\/uploads\/2024\/03\/Quienes-somos-raices.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/","url":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/","name":"Pribatutasun-politika - Txakoli Bengoetxe","isPartOf":{"@id":"https:\/\/www.txakolibengoetxe.com\/eu\/#website"},"datePublished":"2024-02-14T08:15:31+00:00","dateModified":"2024-03-19T16:08:31+00:00","breadcrumb":{"@id":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.txakolibengoetxe.com\/eu\/pribatutasun-politika\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.txakolibengoetxe.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Pribatutasun-politika"}]},{"@type":"WebSite","@id":"https:\/\/www.txakolibengoetxe.com\/eu\/#website","url":"https:\/\/www.txakolibengoetxe.com\/eu\/","name":"Txakoli Bengoetxe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.txakolibengoetxe.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/pages\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/comments?post=430"}],"version-history":[{"count":1,"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/pages\/430\/revisions"}],"predecessor-version":[{"id":431,"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/pages\/430\/revisions\/431"}],"wp:attachment":[{"href":"https:\/\/www.txakolibengoetxe.com\/eu\/wp-json\/wp\/v2\/media?parent=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}